{"id":1633,"date":"2024-07-23T12:17:59","date_gmt":"2024-07-23T04:17:59","guid":{"rendered":"https:\/\/oasiseap.com\/?p=1633"},"modified":"2024-07-23T12:34:41","modified_gmt":"2024-07-23T04:34:41","slug":"%e5%93%a1%e5%b7%a5%e5%8d%94%e5%8a%a9%e6%96%b9%e6%a1%88%ef%bc%88eap%ef%bc%89%ef%bc%9a%e6%8f%90%e5%8d%87%e5%b7%a5%e4%bd%9c%e6%95%88%e8%83%bd%e8%88%87%e7%94%9f%e6%b4%bb%e6%bb%bf%e6%84%8f%e5%ba%a6","status":"publish","type":"post","link":"https:\/\/oasiseap.com\/en\/2024\/07\/23\/%e5%93%a1%e5%b7%a5%e5%8d%94%e5%8a%a9%e6%96%b9%e6%a1%88%ef%bc%88eap%ef%bc%89%ef%bc%9a%e6%8f%90%e5%8d%87%e5%b7%a5%e4%bd%9c%e6%95%88%e8%83%bd%e8%88%87%e7%94%9f%e6%b4%bb%e6%bb%bf%e6%84%8f%e5%ba%a6\/","title":{"rendered":"\u54e1\u5de5\u5354\u52a9\u65b9\u6848\uff08EAP\uff09\uff1a\u63d0\u5347\u5de5\u4f5c\u6548\u80fd\u8207\u751f\u6d3b\u6eff\u610f\u5ea6\u7684\u79d8\u8a23"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">\u5728\u73fe\u4ee3\u8077\u5834\u4e2d\uff0c\u54e1\u5de5\u7684\u5fc3\u7406\u5065\u5eb7\u548c\u5de5\u4f5c\u6548\u80fd\u5df2\u6210\u70ba\u4f01\u696d\u6210\u529f\u7684\u91cd\u8981\u57fa\u77f3\u3002\u7136\u800c\uff0c\u96a8\u8457\u5de5\u4f5c\u58d3\u529b\u7684\u589e\u5927\u548c\u751f\u6d3b\u7bc0\u594f\u7684\u52a0\u5feb\uff0c\u8a31\u591a\u54e1\u5de5\u9762\u81e8\u8457\u5de5\u4f5c\u7f3a\u52e4\u3001\u58d3\u529b\u904e\u5927\u548c\u751f\u6d3b\u6eff\u610f\u5ea6\u4e0b\u964d\u7684\u554f\u984c\u3002\u91dd\u5c0d\u9019\u4e9b\u6311\u6230\uff0c\u54e1\u5de5\u5354\u52a9\u65b9\u6848\uff08Employee Assistance Program, EAP\uff09\u63d0\u4f9b\u4e86\u4e00\u500b\u5f37\u6709\u529b\u7684\u89e3\u6c7a\u65b9\u6848\u3002<\/span><\/p>\n<h2 style=\"font-size: 25px;\"><b>\u4ec0\u9ebc\u662fEAP\uff1f<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">\u54e1\u5de5\u5354\u52a9\u65b9\u6848\uff08EAP\uff09\u662f\u4e00\u9805\u5c08\u70ba\u5e6b\u52a9\u54e1\u5de5\u61c9\u5c0d\u500b\u4eba\u554f\u984c\uff08\u5982\u5fc3\u7406\u5065\u5eb7\u3001\u5bb6\u5ead\u554f\u984c\u3001\u8ca1\u52d9\u56f0\u96e3\u7b49\uff09\u800c\u8a2d\u8a08\u7684\u670d\u52d9\u3002\u9019\u4e9b\u554f\u984c\u82e5\u672a\u80fd\u59a5\u5584\u8655\u7406\uff0c\u53ef\u80fd\u6703\u5c0d\u54e1\u5de5\u7684\u5de5\u4f5c\u6548\u80fd\u548c\u6574\u9ad4\u798f\u7949\u7522\u751f\u8ca0\u9762\u5f71\u97ff\u3002EAP \u901a\u5e38\u7531\u5c08\u696d\u7684\u8aee\u8a62\u5e2b\u63d0\u4f9b\u77ed\u671f\u7684\u3001\u6a5f\u5bc6\u7684\u8aee\u8a62\u670d\u52d9\uff0c\u65e8\u5728\u6539\u5584\u54e1\u5de5\u7684\u751f\u6d3b\u8cea\u91cf\u548c\u5de5\u4f5c\u8868\u73fe\u3002<\/span><\/p>\n<h2 style=\"font-size: 25px;\"><b>EAP\u7684\u6210\u6548\u8207\u6295\u8cc7\u56de\u5831<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">\u6839\u64daEAPA \u300c\u570b\u969b\u54e1\u5de5\u5354\u52a9\u5c08\u696d\u4eba\u54e1\u5354\u6703\u300d\uff08Workplace Outcome Suite, WOS\uff092024\u5e747\u67083\u65e5\u767c\u8868\u7684\u7684\u7814\u7a76\u5831\u544a\uff0cEAP\u54e1\u5de5\u5354\u52a9\u65b9\u6848\u5c0d\u65bc\u63d0\u5347\u54e1\u5de5\u5de5\u4f5c\u6548\u80fd\u548c\u751f\u6d3b\u6eff\u610f\u5ea6\u6709\u8457\u986f\u8457\u7684\u6548\u679c\u3002\u9019\u4efd\u5831\u544a\u5206\u6790\u4e862010\u5e74\u81f32022\u5e74\u9593\u4f86\u81ea61\u500b\u4e0d\u540cEAP\u4f9b\u61c9\u5546\u7684\u8d85\u904e14\u842c\u500b\u8aee\u8a62\u6848\u4f8b\uff0c\u5f97\u51fa\u4e86\u4ee5\u4e0b\u91cd\u8981\u767c\u73fe\uff1a<\/span><\/p>\n<ol>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u5de5\u4f5c\u51fa\u52e4\u7387\u63d0\u5347<\/b><span style=\"font-weight: 400;\">\uff1a\u4f7f\u7528EAP\u5f8c\uff0c\u54e1\u5de5\u7684\u5de5\u4f5c\u51fa\u52e4\u7387\u5f9e\u8aee\u8a62\u524d\u768457%\u986f\u8457\u4e0b\u964d\u5230\u8aee\u8a62\u5f8c\u768434%\u3002<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u751f\u6d3b\u6eff\u610f\u5ea6\u63d0\u5347<\/b><span style=\"font-weight: 400;\">\uff1a\u54e1\u5de5\u7684\u751f\u6d3b\u6eff\u610f\u5ea6\u5f9e\u8aee\u8a62\u524d\u768435%\u4e0a\u5347\u5230\u8aee\u8a62\u5f8c\u768417%\u3002<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u751f\u7522\u529b\u640d\u5931\u6e1b\u5c11<\/b><span style=\"font-weight: 400;\">\uff1a\u6bcf\u6708\u7684\u751f\u7522\u529b\u640d\u5931\u6642\u9593\u5f9e43\u5c0f\u6642\u6e1b\u5c11\u523033\u5c0f\u6642\u3002<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">\u9019\u4e9b\u6578\u64da\u5f37\u8abf\u4e86EAP\u5728\u63d0\u5347\u5de5\u4f5c\u6548\u80fd\u65b9\u9762\u7684\u986f\u8457\u6548\u679c\uff0c\u4e26\u8868\u660eEAP\u8aee\u8a62\u80fd\u6709\u6548\u6e1b\u5c11\u54e1\u5de5\u7684\u5de5\u4f5c\u58d3\u529b\u548c\u7f3a\u52e4\u7387\u3002<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u6b64\u5916\uff0cEAP\u9084\u5177\u6709\u9ad8\u6295\u8cc7\u56de\u5831\u7387\uff08ROI\uff09\u3002\u6839\u64daWOS\u6578\u64da\uff0c\u6bcf\u6295\u8cc71\u7f8e\u5143\u65bcEAP\u54e1\u5de5\u5354\u52a9\u65b9\u6848\uff0c\u4f01\u696d\u5e73\u5747\u53ef\u7372\u5f97\u8d85\u904e5\u7f8e\u5143\u7684\u56de\u5831\uff08ROI\u70ba5.11:1\uff09\u3002\u9019\u4e0d\u50c5\u9ad4\u73fe\u4e86EAP\u5728\u63d0\u5347\u5de5\u4f5c\u6548\u80fd\u548c\u54e1\u5de5\u5e78\u798f\u611f\u65b9\u9762\u7684\u50f9\u503c\uff0c\u9084\u5c55\u793a\u4e86\u5176\u5c0d\u4f01\u696d\u8ca1\u52d9\u6548\u76ca\u7684\u7a4d\u6975\u5f71\u97ff\u3002<\/span><\/p>\n<h2 style=\"font-size: 25px;\"><b>EAP\u7684\u512a\u52e2<\/b><\/h2>\n<ol>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u5168\u65b9\u4f4d\u652f\u6301<\/b><span style=\"font-weight: 400;\">\uff1aEAP \u63d0\u4f9b\u91dd\u5c0d\u5fc3\u7406\u5065\u5eb7\u3001\u8077\u696d\u58d3\u529b\u3001\u5bb6\u5ead\u554f\u984c\u548c\u8ca1\u52d9\u56f0\u96e3\u7b49\u591a\u65b9\u9762\u7684\u652f\u6301\uff0c\u5e6b\u52a9\u54e1\u5de5\u5168\u9762\u63d0\u5347\u751f\u6d3b\u8cea\u91cf\u3002<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u6a5f\u5bc6\u6027\u5f37<\/b><span style=\"font-weight: 400;\">\uff1aEAP\u63d0\u4f9b\u7684\u8aee\u8a62\u670d\u52d9\u5b8c\u5168\u6a5f\u5bc6\uff0c\u78ba\u4fdd\u54e1\u5de5\u80fd\u5920\u653e\u5fc3\u5730\u5c0b\u6c42\u5e6b\u52a9\u800c\u4e0d\u5fc5\u64d4\u5fc3\u96b1\u79c1\u6cc4\u9732\u3002<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u9748\u6d3b\u4fbf\u6377<\/b><span style=\"font-weight: 400;\">\uff1aEAP\u670d\u52d9\u591a\u6578\u901a\u904e\u7dda\u4e0a\u8aee\u8a62\uff0c\u65b9\u4fbf\u54e1\u5de5\u96a8\u6642\u96a8\u5730\u7372\u5f97\u652f\u6301\u3002<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u63d0\u5347\u4f01\u696d\u5f62\u8c61<\/b><span style=\"font-weight: 400;\">\uff1a\u63d0\u4f9bEAP\u7684\u4f01\u696d\u5c55\u793a\u4e86\u5c0d\u54e1\u5de5\u95dc\u61f7\u548c\u652f\u6301\uff0c\u9019\u6709\u52a9\u65bc\u63d0\u5347\u4f01\u696d\u7684\u96c7\u4e3b\u54c1\u724c\u5f62\u8c61\uff0c\u5438\u5f15\u548c\u7559\u4f4f\u512a\u79c0\u4eba\u624d\u3002<\/span><\/li>\n<\/ol>\n<h2 style=\"font-size: 25px;\"><b>\u5be6\u969b\u6848\u4f8b\u5206\u4eab<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">\u8b93\u6211\u5011\u4f86\u770b\u4e00\u770b\u4e00\u4e9b\u5be6\u969b\u6848\u4f8b\uff0c\u9019\u4e9b\u6848\u4f8b\u5c55\u793a\u4e86EAP\u5728\u4e0d\u540c\u60c5\u5883\u4e0b\u7684\u61c9\u7528\u6548\u679c\uff1a<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u6848\u4f8b\u4e00\uff1a\u964d\u4f4e\u58d3\u529b\uff0c\u63d0\u5347\u5de5\u4f5c\u8868\u73fe<\/b><b><br \/>\n<\/b><span style=\"font-weight: 400;\">\u5c0f\u7f8e\u662f\u4e00\u5bb6\u79d1\u6280\u516c\u53f8\u7684\u8edf\u9ad4\u5de5\u7a0b\u5e2b\uff0c\u6700\u8fd1\u56e0\u70ba\u5de5\u4f5c\u58d3\u529b\u5927\u800c\u5e38\u5e38\u5931\u7720\uff0c\u5de5\u4f5c\u6548\u7387\u4e5f\u5927\u5927\u4e0b\u964d\u3002\u5728\u63a5\u53d7\u4e86EAP\u8aee\u8a62\u670d\u52d9\u5f8c\uff0c\u5c0f\u7f8e\u5b78\u6703\u4e86\u58d3\u529b\u7ba1\u7406\u6280\u5de7\uff0c\u4e26\u5f97\u5230\u4e86\u5fc3\u7406\u8f14\u5c0e\uff0c\u6700\u7d42\u6210\u529f\u6539\u5584\u4e86\u7761\u7720\u8cea\u91cf\u548c\u5de5\u4f5c\u8868\u73fe\u3002<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u6848\u4f8b\u4e8c\uff1a\u8655\u7406\u5bb6\u5ead\u554f\u984c\uff0c\u91cd\u56de\u5de5\u4f5c\u6b63\u8ecc<\/b><b><br \/>\n<\/b><span style=\"font-weight: 400;\">\u5927\u885b\u662f\u4e00\u5bb6\u88fd\u9020\u4f01\u696d\u7684\u7ba1\u7406\u5c64\uff0c\u56e0\u70ba\u5bb6\u5ead\u554f\u984c\u800c\u7121\u6cd5\u5c08\u5fc3\u5de5\u4f5c\uff0c\u7d93\u5e38\u9072\u5230\u65e9\u9000\u3002\u901a\u904eEAP\u7684\u5e6b\u52a9\uff0c\u4ed6\u5f97\u5230\u4e86\u5bb6\u5ead\u554f\u984c\u7684\u5c08\u696d\u8f14\u5c0e\uff0c\u4e26\u91cd\u65b0\u627e\u56de\u4e86\u5de5\u4f5c\u8207\u751f\u6d3b\u7684\u5e73\u8861\u3002<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u6848\u4f8b\u4e09\uff1a\u8ca1\u52d9\u56f0\u5883\uff0c\u8d70\u51fa\u4f4e\u8c37<\/b><b><br \/>\n<\/b><span style=\"font-weight: 400;\">\u674e\u5148\u751f\u662f\u4e00\u5bb6\u96f6\u552e\u516c\u53f8\u7684\u54e1\u5de5\uff0c\u56e0\u8ca1\u52d9\u56f0\u96e3\u5c0e\u81f4\u5de5\u4f5c\u58d3\u529b\u5de8\u5927\u3002EAP\u63d0\u4f9b\u4e86\u5c08\u696d\u7684\u8ca1\u52d9\u8aee\u8a62\u670d\u52d9\uff0c\u5e6b\u52a9\u4ed6\u5236\u5b9a\u4e86\u5408\u7406\u7684\u8ca1\u52d9\u8a08\u5283\uff0c\u9010\u6b65\u8d70\u51fa\u4e86\u56f0\u5883\uff0c\u91cd\u62fe\u4fe1\u5fc3\u3002<\/span><\/li>\n<\/ul>\n<h2 style=\"font-size: 25px;\"><b>\u70ba\u4f55\u9078\u64c7 OasisEAP\uff1f<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">\u5728\u773e\u591aEAP\u4f9b\u61c9\u5546\u4e2d\uff0cOasisEAP \u4ee5\u5176\u5c08\u696d\u6027\u548c\u9ad8\u6548\u6027\u812b\u7a4e\u800c\u51fa\u3002\u6211\u5011\u81f4\u529b\u65bc\u63d0\u4f9b\u6700\u5c08\u696d\u7684\u54e1\u5de5\u5354\u52a9\u65b9\u6848\uff0c\u5e6b\u52a9\u4f01\u696d\u63d0\u5347\u54e1\u5de5\u7684\u5de5\u4f5c\u6548\u80fd\u548c\u751f\u6d3b\u6eff\u610f\u5ea6\u3002OasisEAP \u7684\u670d\u52d9\u7279\u8272\u5305\u62ec\uff1a<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u500b\u6027\u5316\u670d\u52d9<\/b><span style=\"font-weight: 400;\">\uff1a\u6839\u64da\u6bcf\u4f4d\u54e1\u5de5\u7684\u5177\u9ad4\u9700\u6c42\uff0c\u63d0\u4f9b\u91cf\u8eab\u5b9a\u5236\u7684\u8aee\u8a62\u548c\u652f\u6301\u3002<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Our Teams<\/b><span style=\"font-weight: 400;\">\uff1a\u64c1\u6709\u8c50\u5bcc\u7d93\u9a57\u7684\u5fc3\u7406\u8aee\u5546\u5e2b\u548c\u6cd5\u5f8b\u9867\u554f\u53ca\u8ca1\u52d9\u9867\u554f\uff0c\u78ba\u4fdd\u63d0\u4f9b\u6700\u5c08\u696d\u7684\u5e6b\u52a9\u3002<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u5168\u65b9\u4f4d\u652f\u6301<\/b><span style=\"font-weight: 400;\">\uff1a\u6db5\u84cb\u5fc3\u7406\u5065\u5eb7\u3001\u8077\u696d\u767c\u5c55\u3001\u58d3\u529b\u7ba1\u7406\u548c\u751f\u6d3b\u5e73\u8861\u7b49\u591a\u65b9\u9762\u3002<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">\u6b64\u5916\uff0cOasisEAP \u63d0\u4f9b\u7684\u670d\u52d9\u4e0d\u50c5\u9650\u65bc\u50b3\u7d71\u7684\u9762\u5c0d\u9762\u8aee\u8a62\uff0c\u9084\u5305\u62ec\u96fb\u8a71\u548c\u7dda\u4e0a\u8aee\u8a62\uff0c\u9748\u6d3b\u591a\u6a23\u7684\u670d\u52d9\u6a21\u5f0f\u80fd\u5920\u6eff\u8db3\u4e0d\u540c\u54e1\u5de5\u7684\u9700\u6c42\u3002\u901a\u904e\u8207OasisEAP\u5408\u4f5c\uff0c\u4f01\u696d\u4e0d\u50c5\u80fd\u5920\u63d0\u5347\u54e1\u5de5\u7684\u5de5\u4f5c\u6548\u80fd\u548c\u5e78\u798f\u611f\uff0c\u9084\u80fd\u964d\u4f4e\u56e0\u54e1\u5de5\u58d3\u529b\u548c\u7f3a\u52e4\u9020\u6210\u7684\u640d\u5931\uff0c\u5be6\u73fe\u96d9\u8d0f\u7684\u5c40\u9762\u3002<\/span><\/p>\n<h2 style=\"font-size: 25px;\"><b>\u672a\u4f86\u5c55\u671b<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">\u96a8\u8457EAP\u7684\u666e\u53ca\u548c\u61c9\u7528\uff0c\u8d8a\u4f86\u8d8a\u591a\u7684\u4f01\u696d\u8a8d\u8b58\u5230\u5176\u5c0d\u63d0\u5347\u54e1\u5de5\u6548\u80fd\u548c\u4f01\u696d\u7af6\u722d\u529b\u7684\u5de8\u5927\u50f9\u503c\u3002\u5728\u672a\u4f86\uff0c\u6211\u5011\u76f8\u4fe1EAP\u5c07\u6210\u70ba\u6bcf\u500b\u6210\u529f\u4f01\u696d\u4e0d\u53ef\u6216\u7f3a\u7684\u4e00\u90e8\u5206\uff0c\u5e6b\u52a9\u4f01\u696d\u5275\u9020\u4e00\u500b\u66f4\u5065\u5eb7\u3001\u66f4\u9ad8\u6548\u7684\u5de5\u4f5c\u74b0\u5883\u3002<\/span><\/p>\n<h2 style=\"font-size: 25px;\">\u63d0\u4f9b\u514d\u8cbb EAP \u8aee\u8a62<\/h2>\n<p><span style=\"font-weight: 400;\">\u900f\u904eOasisEAP\uff0c\u60a8\u7684\u4f01\u696d\u5c07\u4e0d\u50c5\u63d0\u5347\u54e1\u5de5\u7684\u5de5\u4f5c\u6548\u80fd\uff0c\u9084\u80fd\u589e\u5f37\u6574\u9ad4\u7684\u4f01\u696d\u7af6\u722d\u529b\u3002\u7acb\u5373<a href=\"https:\/\/oasiseap.com\/en\/%e8%81%af%e7%b5%a1%e6%88%91%e5%80%91\/\">\u806f\u7e6b\u6211\u5011<\/a>\uff0c\u514d\u8cbb\u4e86\u89e3\u5982\u4f55\u70ba\u60a8\u7684\u4f01\u696d\u5982\u4f55\u5f15\u5165\u54e1\u5de5\u5354\u52a9\u65b9\u6848\uff0c\u6253\u9020\u66f4\u5065\u5eb7\u3001\u66f4\u9ad8\u6548\u7684\u5de5\u4f5c\u74b0\u5883\u3002<\/span><\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>\u5728\u73fe\u4ee3\u8077\u5834\u4e2d\uff0c\u54e1\u5de5\u7684\u5fc3\u7406\u5065\u5eb7\u548c\u5de5\u4f5c\u6548\u80fd\u5df2 [&hellip;]<\/p>","protected":false},"author":5,"featured_media":1639,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[24,25],"post_folder":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u54e1\u5de5\u5354\u52a9\u65b9\u6848\uff08EAP\uff09\uff1a\u63d0\u5347\u5de5\u4f5c\u6548\u80fd\u8207\u751f\u6d3b\u6eff\u610f\u5ea6\u7684\u79d8\u8a23 - \u7da0\u6d32\u7ba1\u7406\u9867\u554f\u80a1\u4efd\u6709\u9650\u516c\u53f8<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/oasiseap.com\/en\/2024\/07\/23\/\u54e1\u5de5\u5354\u52a9\u65b9\u6848\uff08eap\uff09\uff1a\u63d0\u5347\u5de5\u4f5c\u6548\u80fd\u8207\u751f\u6d3b\u6eff\u610f\u5ea6\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u54e1\u5de5\u5354\u52a9\u65b9\u6848\uff08EAP\uff09\uff1a\u63d0\u5347\u5de5\u4f5c\u6548\u80fd\u8207\u751f\u6d3b\u6eff\u610f\u5ea6\u7684\u79d8\u8a23 - \u7da0\u6d32\u7ba1\u7406\u9867\u554f\u80a1\u4efd\u6709\u9650\u516c\u53f8\" \/>\n<meta property=\"og:description\" content=\"\u5728\u73fe\u4ee3\u8077\u5834\u4e2d\uff0c\u54e1\u5de5\u7684\u5fc3\u7406\u5065\u5eb7\u548c\u5de5\u4f5c\u6548\u80fd\u5df2 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/oasiseap.com\/en\/2024\/07\/23\/\u54e1\u5de5\u5354\u52a9\u65b9\u6848\uff08eap\uff09\uff1a\u63d0\u5347\u5de5\u4f5c\u6548\u80fd\u8207\u751f\u6d3b\u6eff\u610f\u5ea6\/\" \/>\n<meta property=\"og:site_name\" content=\"\u7da0\u6d32\u7ba1\u7406\u9867\u554f\u80a1\u4efd\u6709\u9650\u516c\u53f8\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-23T04:17:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-23T04:34:41+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/oasiseap.com\/wp-content\/uploads\/2024\/07\/\u5beb\u4e0b\u4f60\u7684-\u4e3b\u984c\u6216\u60f3\u6cd5-2-1-300x169-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"169\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"stephanie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"stephanie\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/oasiseap.com\/en\/2024\/07\/23\/%e5%93%a1%e5%b7%a5%e5%8d%94%e5%8a%a9%e6%96%b9%e6%a1%88%ef%bc%88eap%ef%bc%89%ef%bc%9a%e6%8f%90%e5%8d%87%e5%b7%a5%e4%bd%9c%e6%95%88%e8%83%bd%e8%88%87%e7%94%9f%e6%b4%bb%e6%bb%bf%e6%84%8f%e5%ba%a6\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/oasiseap.com\/en\/2024\/07\/23\/%e5%93%a1%e5%b7%a5%e5%8d%94%e5%8a%a9%e6%96%b9%e6%a1%88%ef%bc%88eap%ef%bc%89%ef%bc%9a%e6%8f%90%e5%8d%87%e5%b7%a5%e4%bd%9c%e6%95%88%e8%83%bd%e8%88%87%e7%94%9f%e6%b4%bb%e6%bb%bf%e6%84%8f%e5%ba%a6\/\"},\"author\":{\"name\":\"stephanie\",\"@id\":\"https:\/\/oasiseap.com\/#\/schema\/person\/f56fe43dcb96b036737679dd6fcb99ca\"},\"headline\":\"\u54e1\u5de5\u5354\u52a9\u65b9\u6848\uff08EAP\uff09\uff1a\u63d0\u5347\u5de5\u4f5c\u6548\u80fd\u8207\u751f\u6d3b\u6eff\u610f\u5ea6\u7684\u79d8\u8a23\",\"datePublished\":\"2024-07-23T04:17:59+00:00\",\"dateModified\":\"2024-07-23T04:34:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/oasiseap.com\/en\/2024\/07\/23\/%e5%93%a1%e5%b7%a5%e5%8d%94%e5%8a%a9%e6%96%b9%e6%a1%88%ef%bc%88eap%ef%bc%89%ef%bc%9a%e6%8f%90%e5%8d%87%e5%b7%a5%e4%bd%9c%e6%95%88%e8%83%bd%e8%88%87%e7%94%9f%e6%b4%bb%e6%bb%bf%e6%84%8f%e5%ba%a6\/\"},\"wordCount\":45,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/oasiseap.com\/#organization\"},\"image\":{\"@id\":\"http:\/\/oasiseap.com\/en\/2024\/07\/23\/%e5%93%a1%e5%b7%a5%e5%8d%94%e5%8a%a9%e6%96%b9%e6%a1%88%ef%bc%88eap%ef%bc%89%ef%bc%9a%e6%8f%90%e5%8d%87%e5%b7%a5%e4%bd%9c%e6%95%88%e8%83%bd%e8%88%87%e7%94%9f%e6%b4%bb%e6%bb%bf%e6%84%8f%e5%ba%a6\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/oasiseap.com\/wp-content\/uploads\/2024\/07\/\u5beb\u4e0b\u4f60\u7684-\u4e3b\u984c\u6216\u60f3\u6cd5-2-1-300x169-1.jpg\",\"keywords\":[\"EAP\",\"\u54e1\u5de5\u5354\u52a9\u65b9\u6848\"],\"articleSection\":[\"\u6700\u65b0\u6d88\u606f\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/oasiseap.com\/en\/2024\/07\/23\/%e5%93%a1%e5%b7%a5%e5%8d%94%e5%8a%a9%e6%96%b9%e6%a1%88%ef%bc%88eap%ef%bc%89%ef%bc%9a%e6%8f%90%e5%8d%87%e5%b7%a5%e4%bd%9c%e6%95%88%e8%83%bd%e8%88%87%e7%94%9f%e6%b4%bb%e6%bb%bf%e6%84%8f%e5%ba%a6\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/oasiseap.com\/en\/2024\/07\/23\/%e5%93%a1%e5%b7%a5%e5%8d%94%e5%8a%a9%e6%96%b9%e6%a1%88%ef%bc%88eap%ef%bc%89%ef%bc%9a%e6%8f%90%e5%8d%87%e5%b7%a5%e4%bd%9c%e6%95%88%e8%83%bd%e8%88%87%e7%94%9f%e6%b4%bb%e6%bb%bf%e6%84%8f%e5%ba%a6\/\",\"url\":\"http:\/\/oasiseap.com\/en\/2024\/07\/23\/%e5%93%a1%e5%b7%a5%e5%8d%94%e5%8a%a9%e6%96%b9%e6%a1%88%ef%bc%88eap%ef%bc%89%ef%bc%9a%e6%8f%90%e5%8d%87%e5%b7%a5%e4%bd%9c%e6%95%88%e8%83%bd%e8%88%87%e7%94%9f%e6%b4%bb%e6%bb%bf%e6%84%8f%e5%ba%a6\/\",\"name\":\"\u54e1\u5de5\u5354\u52a9\u65b9\u6848\uff08EAP\uff09\uff1a\u63d0\u5347\u5de5\u4f5c\u6548\u80fd\u8207\u751f\u6d3b\u6eff\u610f\u5ea6\u7684\u79d8\u8a23 - \u7da0\u6d32\u7ba1\u7406\u9867\u554f\u80a1\u4efd\u6709\u9650\u516c\u53f8\",\"isPartOf\":{\"@id\":\"https:\/\/oasiseap.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/oasiseap.com\/en\/2024\/07\/23\/%e5%93%a1%e5%b7%a5%e5%8d%94%e5%8a%a9%e6%96%b9%e6%a1%88%ef%bc%88eap%ef%bc%89%ef%bc%9a%e6%8f%90%e5%8d%87%e5%b7%a5%e4%bd%9c%e6%95%88%e8%83%bd%e8%88%87%e7%94%9f%e6%b4%bb%e6%bb%bf%e6%84%8f%e5%ba%a6\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/oasiseap.com\/en\/2024\/07\/23\/%e5%93%a1%e5%b7%a5%e5%8d%94%e5%8a%a9%e6%96%b9%e6%a1%88%ef%bc%88eap%ef%bc%89%ef%bc%9a%e6%8f%90%e5%8d%87%e5%b7%a5%e4%bd%9c%e6%95%88%e8%83%bd%e8%88%87%e7%94%9f%e6%b4%bb%e6%bb%bf%e6%84%8f%e5%ba%a6\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/oasiseap.com\/wp-content\/uploads\/2024\/07\/\u5beb\u4e0b\u4f60\u7684-\u4e3b\u984c\u6216\u60f3\u6cd5-2-1-300x169-1.jpg\",\"datePublished\":\"2024-07-23T04:17:59+00:00\",\"dateModified\":\"2024-07-23T04:34:41+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/oasiseap.com\/en\/2024\/07\/23\/%e5%93%a1%e5%b7%a5%e5%8d%94%e5%8a%a9%e6%96%b9%e6%a1%88%ef%bc%88eap%ef%bc%89%ef%bc%9a%e6%8f%90%e5%8d%87%e5%b7%a5%e4%bd%9c%e6%95%88%e8%83%bd%e8%88%87%e7%94%9f%e6%b4%bb%e6%bb%bf%e6%84%8f%e5%ba%a6\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/oasiseap.com\/en\/2024\/07\/23\/%e5%93%a1%e5%b7%a5%e5%8d%94%e5%8a%a9%e6%96%b9%e6%a1%88%ef%bc%88eap%ef%bc%89%ef%bc%9a%e6%8f%90%e5%8d%87%e5%b7%a5%e4%bd%9c%e6%95%88%e8%83%bd%e8%88%87%e7%94%9f%e6%b4%bb%e6%bb%bf%e6%84%8f%e5%ba%a6\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\/\/oasiseap.com\/en\/2024\/07\/23\/%e5%93%a1%e5%b7%a5%e5%8d%94%e5%8a%a9%e6%96%b9%e6%a1%88%ef%bc%88eap%ef%bc%89%ef%bc%9a%e6%8f%90%e5%8d%87%e5%b7%a5%e4%bd%9c%e6%95%88%e8%83%bd%e8%88%87%e7%94%9f%e6%b4%bb%e6%bb%bf%e6%84%8f%e5%ba%a6\/#primaryimage\",\"url\":\"https:\/\/oasiseap.com\/wp-content\/uploads\/2024\/07\/\u5beb\u4e0b\u4f60\u7684-\u4e3b\u984c\u6216\u60f3\u6cd5-2-1-300x169-1.jpg\",\"contentUrl\":\"https:\/\/oasiseap.com\/wp-content\/uploads\/2024\/07\/\u5beb\u4e0b\u4f60\u7684-\u4e3b\u984c\u6216\u60f3\u6cd5-2-1-300x169-1.jpg\",\"width\":300,\"height\":169},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/oasiseap.com\/en\/2024\/07\/23\/%e5%93%a1%e5%b7%a5%e5%8d%94%e5%8a%a9%e6%96%b9%e6%a1%88%ef%bc%88eap%ef%bc%89%ef%bc%9a%e6%8f%90%e5%8d%87%e5%b7%a5%e4%bd%9c%e6%95%88%e8%83%bd%e8%88%87%e7%94%9f%e6%b4%bb%e6%bb%bf%e6%84%8f%e5%ba%a6\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u9996\u9801\",\"item\":\"https:\/\/oasiseap.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u54e1\u5de5\u5354\u52a9\u65b9\u6848\uff08EAP\uff09\uff1a\u63d0\u5347\u5de5\u4f5c\u6548\u80fd\u8207\u751f\u6d3b\u6eff\u610f\u5ea6\u7684\u79d8\u8a23\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/oasiseap.com\/#website\",\"url\":\"https:\/\/oasiseap.com\/\",\"name\":\"\u7da0\u6d32\u7ba1\u7406\u9867\u554f\u80a1\u4efd\u6709\u9650\u516c\u53f8\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/oasiseap.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/oasiseap.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/oasiseap.com\/#organization\",\"name\":\"\u7da0\u6d32\u7ba1\u7406\u9867\u554f\u80a1\u4efd\u6709\u9650\u516c\u53f8\",\"url\":\"https:\/\/oasiseap.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/oasiseap.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/oasiseap.com\/wp-content\/uploads\/2024\/03\/\u539f\u59cb\u6a94_\u7da0\u6d32\u7ba1\u7406\u9867\u554f_LOGO.png\",\"contentUrl\":\"https:\/\/oasiseap.com\/wp-content\/uploads\/2024\/03\/\u539f\u59cb\u6a94_\u7da0\u6d32\u7ba1\u7406\u9867\u554f_LOGO.png\",\"width\":4231,\"height\":1153,\"caption\":\"\u7da0\u6d32\u7ba1\u7406\u9867\u554f\u80a1\u4efd\u6709\u9650\u516c\u53f8\"},\"image\":{\"@id\":\"https:\/\/oasiseap.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/oasiseap.com\/#\/schema\/person\/f56fe43dcb96b036737679dd6fcb99ca\",\"name\":\"stephanie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/oasiseap.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e97a06737e9092e44ef9bc69fa2dd635?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e97a06737e9092e44ef9bc69fa2dd635?s=96&d=mm&r=g\",\"caption\":\"stephanie\"},\"url\":\"https:\/\/oasiseap.com\/en\/author\/stephanie\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u54e1\u5de5\u5354\u52a9\u65b9\u6848\uff08EAP\uff09\uff1a\u63d0\u5347\u5de5\u4f5c\u6548\u80fd\u8207\u751f\u6d3b\u6eff\u610f\u5ea6\u7684\u79d8\u8a23 - \u7da0\u6d32\u7ba1\u7406\u9867\u554f\u80a1\u4efd\u6709\u9650\u516c\u53f8","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/oasiseap.com\/en\/2024\/07\/23\/\u54e1\u5de5\u5354\u52a9\u65b9\u6848\uff08eap\uff09\uff1a\u63d0\u5347\u5de5\u4f5c\u6548\u80fd\u8207\u751f\u6d3b\u6eff\u610f\u5ea6\/","og_locale":"en_US","og_type":"article","og_title":"\u54e1\u5de5\u5354\u52a9\u65b9\u6848\uff08EAP\uff09\uff1a\u63d0\u5347\u5de5\u4f5c\u6548\u80fd\u8207\u751f\u6d3b\u6eff\u610f\u5ea6\u7684\u79d8\u8a23 - \u7da0\u6d32\u7ba1\u7406\u9867\u554f\u80a1\u4efd\u6709\u9650\u516c\u53f8","og_description":"\u5728\u73fe\u4ee3\u8077\u5834\u4e2d\uff0c\u54e1\u5de5\u7684\u5fc3\u7406\u5065\u5eb7\u548c\u5de5\u4f5c\u6548\u80fd\u5df2 [&hellip;]","og_url":"http:\/\/oasiseap.com\/en\/2024\/07\/23\/\u54e1\u5de5\u5354\u52a9\u65b9\u6848\uff08eap\uff09\uff1a\u63d0\u5347\u5de5\u4f5c\u6548\u80fd\u8207\u751f\u6d3b\u6eff\u610f\u5ea6\/","og_site_name":"\u7da0\u6d32\u7ba1\u7406\u9867\u554f\u80a1\u4efd\u6709\u9650\u516c\u53f8","article_published_time":"2024-07-23T04:17:59+00:00","article_modified_time":"2024-07-23T04:34:41+00:00","og_image":[{"width":300,"height":169,"url":"http:\/\/oasiseap.com\/wp-content\/uploads\/2024\/07\/\u5beb\u4e0b\u4f60\u7684-\u4e3b\u984c\u6216\u60f3\u6cd5-2-1-300x169-1.jpg","type":"image\/jpeg"}],"author":"stephanie","twitter_card":"summary_large_image","twitter_misc":{"Written by":"stephanie","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/oasiseap.com\/en\/2024\/07\/23\/%e5%93%a1%e5%b7%a5%e5%8d%94%e5%8a%a9%e6%96%b9%e6%a1%88%ef%bc%88eap%ef%bc%89%ef%bc%9a%e6%8f%90%e5%8d%87%e5%b7%a5%e4%bd%9c%e6%95%88%e8%83%bd%e8%88%87%e7%94%9f%e6%b4%bb%e6%bb%bf%e6%84%8f%e5%ba%a6\/#article","isPartOf":{"@id":"http:\/\/oasiseap.com\/en\/2024\/07\/23\/%e5%93%a1%e5%b7%a5%e5%8d%94%e5%8a%a9%e6%96%b9%e6%a1%88%ef%bc%88eap%ef%bc%89%ef%bc%9a%e6%8f%90%e5%8d%87%e5%b7%a5%e4%bd%9c%e6%95%88%e8%83%bd%e8%88%87%e7%94%9f%e6%b4%bb%e6%bb%bf%e6%84%8f%e5%ba%a6\/"},"author":{"name":"stephanie","@id":"https:\/\/oasiseap.com\/#\/schema\/person\/f56fe43dcb96b036737679dd6fcb99ca"},"headline":"\u54e1\u5de5\u5354\u52a9\u65b9\u6848\uff08EAP\uff09\uff1a\u63d0\u5347\u5de5\u4f5c\u6548\u80fd\u8207\u751f\u6d3b\u6eff\u610f\u5ea6\u7684\u79d8\u8a23","datePublished":"2024-07-23T04:17:59+00:00","dateModified":"2024-07-23T04:34:41+00:00","mainEntityOfPage":{"@id":"http:\/\/oasiseap.com\/en\/2024\/07\/23\/%e5%93%a1%e5%b7%a5%e5%8d%94%e5%8a%a9%e6%96%b9%e6%a1%88%ef%bc%88eap%ef%bc%89%ef%bc%9a%e6%8f%90%e5%8d%87%e5%b7%a5%e4%bd%9c%e6%95%88%e8%83%bd%e8%88%87%e7%94%9f%e6%b4%bb%e6%bb%bf%e6%84%8f%e5%ba%a6\/"},"wordCount":45,"commentCount":0,"publisher":{"@id":"https:\/\/oasiseap.com\/#organization"},"image":{"@id":"http:\/\/oasiseap.com\/en\/2024\/07\/23\/%e5%93%a1%e5%b7%a5%e5%8d%94%e5%8a%a9%e6%96%b9%e6%a1%88%ef%bc%88eap%ef%bc%89%ef%bc%9a%e6%8f%90%e5%8d%87%e5%b7%a5%e4%bd%9c%e6%95%88%e8%83%bd%e8%88%87%e7%94%9f%e6%b4%bb%e6%bb%bf%e6%84%8f%e5%ba%a6\/#primaryimage"},"thumbnailUrl":"https:\/\/oasiseap.com\/wp-content\/uploads\/2024\/07\/\u5beb\u4e0b\u4f60\u7684-\u4e3b\u984c\u6216\u60f3\u6cd5-2-1-300x169-1.jpg","keywords":["EAP","\u54e1\u5de5\u5354\u52a9\u65b9\u6848"],"articleSection":["\u6700\u65b0\u6d88\u606f"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/oasiseap.com\/en\/2024\/07\/23\/%e5%93%a1%e5%b7%a5%e5%8d%94%e5%8a%a9%e6%96%b9%e6%a1%88%ef%bc%88eap%ef%bc%89%ef%bc%9a%e6%8f%90%e5%8d%87%e5%b7%a5%e4%bd%9c%e6%95%88%e8%83%bd%e8%88%87%e7%94%9f%e6%b4%bb%e6%bb%bf%e6%84%8f%e5%ba%a6\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/oasiseap.com\/en\/2024\/07\/23\/%e5%93%a1%e5%b7%a5%e5%8d%94%e5%8a%a9%e6%96%b9%e6%a1%88%ef%bc%88eap%ef%bc%89%ef%bc%9a%e6%8f%90%e5%8d%87%e5%b7%a5%e4%bd%9c%e6%95%88%e8%83%bd%e8%88%87%e7%94%9f%e6%b4%bb%e6%bb%bf%e6%84%8f%e5%ba%a6\/","url":"http:\/\/oasiseap.com\/en\/2024\/07\/23\/%e5%93%a1%e5%b7%a5%e5%8d%94%e5%8a%a9%e6%96%b9%e6%a1%88%ef%bc%88eap%ef%bc%89%ef%bc%9a%e6%8f%90%e5%8d%87%e5%b7%a5%e4%bd%9c%e6%95%88%e8%83%bd%e8%88%87%e7%94%9f%e6%b4%bb%e6%bb%bf%e6%84%8f%e5%ba%a6\/","name":"\u54e1\u5de5\u5354\u52a9\u65b9\u6848\uff08EAP\uff09\uff1a\u63d0\u5347\u5de5\u4f5c\u6548\u80fd\u8207\u751f\u6d3b\u6eff\u610f\u5ea6\u7684\u79d8\u8a23 - \u7da0\u6d32\u7ba1\u7406\u9867\u554f\u80a1\u4efd\u6709\u9650\u516c\u53f8","isPartOf":{"@id":"https:\/\/oasiseap.com\/#website"},"primaryImageOfPage":{"@id":"http:\/\/oasiseap.com\/en\/2024\/07\/23\/%e5%93%a1%e5%b7%a5%e5%8d%94%e5%8a%a9%e6%96%b9%e6%a1%88%ef%bc%88eap%ef%bc%89%ef%bc%9a%e6%8f%90%e5%8d%87%e5%b7%a5%e4%bd%9c%e6%95%88%e8%83%bd%e8%88%87%e7%94%9f%e6%b4%bb%e6%bb%bf%e6%84%8f%e5%ba%a6\/#primaryimage"},"image":{"@id":"http:\/\/oasiseap.com\/en\/2024\/07\/23\/%e5%93%a1%e5%b7%a5%e5%8d%94%e5%8a%a9%e6%96%b9%e6%a1%88%ef%bc%88eap%ef%bc%89%ef%bc%9a%e6%8f%90%e5%8d%87%e5%b7%a5%e4%bd%9c%e6%95%88%e8%83%bd%e8%88%87%e7%94%9f%e6%b4%bb%e6%bb%bf%e6%84%8f%e5%ba%a6\/#primaryimage"},"thumbnailUrl":"https:\/\/oasiseap.com\/wp-content\/uploads\/2024\/07\/\u5beb\u4e0b\u4f60\u7684-\u4e3b\u984c\u6216\u60f3\u6cd5-2-1-300x169-1.jpg","datePublished":"2024-07-23T04:17:59+00:00","dateModified":"2024-07-23T04:34:41+00:00","breadcrumb":{"@id":"http:\/\/oasiseap.com\/en\/2024\/07\/23\/%e5%93%a1%e5%b7%a5%e5%8d%94%e5%8a%a9%e6%96%b9%e6%a1%88%ef%bc%88eap%ef%bc%89%ef%bc%9a%e6%8f%90%e5%8d%87%e5%b7%a5%e4%bd%9c%e6%95%88%e8%83%bd%e8%88%87%e7%94%9f%e6%b4%bb%e6%bb%bf%e6%84%8f%e5%ba%a6\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/oasiseap.com\/en\/2024\/07\/23\/%e5%93%a1%e5%b7%a5%e5%8d%94%e5%8a%a9%e6%96%b9%e6%a1%88%ef%bc%88eap%ef%bc%89%ef%bc%9a%e6%8f%90%e5%8d%87%e5%b7%a5%e4%bd%9c%e6%95%88%e8%83%bd%e8%88%87%e7%94%9f%e6%b4%bb%e6%bb%bf%e6%84%8f%e5%ba%a6\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/oasiseap.com\/en\/2024\/07\/23\/%e5%93%a1%e5%b7%a5%e5%8d%94%e5%8a%a9%e6%96%b9%e6%a1%88%ef%bc%88eap%ef%bc%89%ef%bc%9a%e6%8f%90%e5%8d%87%e5%b7%a5%e4%bd%9c%e6%95%88%e8%83%bd%e8%88%87%e7%94%9f%e6%b4%bb%e6%bb%bf%e6%84%8f%e5%ba%a6\/#primaryimage","url":"https:\/\/oasiseap.com\/wp-content\/uploads\/2024\/07\/\u5beb\u4e0b\u4f60\u7684-\u4e3b\u984c\u6216\u60f3\u6cd5-2-1-300x169-1.jpg","contentUrl":"https:\/\/oasiseap.com\/wp-content\/uploads\/2024\/07\/\u5beb\u4e0b\u4f60\u7684-\u4e3b\u984c\u6216\u60f3\u6cd5-2-1-300x169-1.jpg","width":300,"height":169},{"@type":"BreadcrumbList","@id":"http:\/\/oasiseap.com\/en\/2024\/07\/23\/%e5%93%a1%e5%b7%a5%e5%8d%94%e5%8a%a9%e6%96%b9%e6%a1%88%ef%bc%88eap%ef%bc%89%ef%bc%9a%e6%8f%90%e5%8d%87%e5%b7%a5%e4%bd%9c%e6%95%88%e8%83%bd%e8%88%87%e7%94%9f%e6%b4%bb%e6%bb%bf%e6%84%8f%e5%ba%a6\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9801","item":"https:\/\/oasiseap.com\/"},{"@type":"ListItem","position":2,"name":"\u54e1\u5de5\u5354\u52a9\u65b9\u6848\uff08EAP\uff09\uff1a\u63d0\u5347\u5de5\u4f5c\u6548\u80fd\u8207\u751f\u6d3b\u6eff\u610f\u5ea6\u7684\u79d8\u8a23"}]},{"@type":"WebSite","@id":"https:\/\/oasiseap.com\/#website","url":"https:\/\/oasiseap.com\/","name":"\u7da0\u6d32\u7ba1\u7406\u9867\u554f\u80a1\u4efd\u6709\u9650\u516c\u53f8","description":"","publisher":{"@id":"https:\/\/oasiseap.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oasiseap.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/oasiseap.com\/#organization","name":"\u7da0\u6d32\u7ba1\u7406\u9867\u554f\u80a1\u4efd\u6709\u9650\u516c\u53f8","url":"https:\/\/oasiseap.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/oasiseap.com\/#\/schema\/logo\/image\/","url":"https:\/\/oasiseap.com\/wp-content\/uploads\/2024\/03\/\u539f\u59cb\u6a94_\u7da0\u6d32\u7ba1\u7406\u9867\u554f_LOGO.png","contentUrl":"https:\/\/oasiseap.com\/wp-content\/uploads\/2024\/03\/\u539f\u59cb\u6a94_\u7da0\u6d32\u7ba1\u7406\u9867\u554f_LOGO.png","width":4231,"height":1153,"caption":"\u7da0\u6d32\u7ba1\u7406\u9867\u554f\u80a1\u4efd\u6709\u9650\u516c\u53f8"},"image":{"@id":"https:\/\/oasiseap.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/oasiseap.com\/#\/schema\/person\/f56fe43dcb96b036737679dd6fcb99ca","name":"stephanie","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/oasiseap.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e97a06737e9092e44ef9bc69fa2dd635?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e97a06737e9092e44ef9bc69fa2dd635?s=96&d=mm&r=g","caption":"stephanie"},"url":"https:\/\/oasiseap.com\/en\/author\/stephanie\/"}]}},"_links":{"self":[{"href":"https:\/\/oasiseap.com\/en\/wp-json\/wp\/v2\/posts\/1633"}],"collection":[{"href":"https:\/\/oasiseap.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/oasiseap.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/oasiseap.com\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/oasiseap.com\/en\/wp-json\/wp\/v2\/comments?post=1633"}],"version-history":[{"count":6,"href":"https:\/\/oasiseap.com\/en\/wp-json\/wp\/v2\/posts\/1633\/revisions"}],"predecessor-version":[{"id":1640,"href":"https:\/\/oasiseap.com\/en\/wp-json\/wp\/v2\/posts\/1633\/revisions\/1640"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/oasiseap.com\/en\/wp-json\/wp\/v2\/media\/1639"}],"wp:attachment":[{"href":"https:\/\/oasiseap.com\/en\/wp-json\/wp\/v2\/media?parent=1633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/oasiseap.com\/en\/wp-json\/wp\/v2\/categories?post=1633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/oasiseap.com\/en\/wp-json\/wp\/v2\/tags?post=1633"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/oasiseap.com\/en\/wp-json\/wp\/v2\/post_folder?post=1633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}